{"id":419,"count":10,"description":"<em>Du guerrier partant batailler au laboureur souhaitant travailler, l\u2019\u00e9levage des chevaux est un art mill\u00e9naire. D\u00e9couvrez son actualit\u00e9 dans cette cat\u00e9gorie.<\/em>","link":"https:\/\/www.royal-horse.com\/fr\/wikihorse\/elevage\/","name":"\u00c9levage","slug":"elevage","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des \u00c9levage - Royal Horse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.royal-horse.com\/fr\/wikihorse\/elevage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des \u00c9levage - Royal Horse\" \/>\n<meta property=\"og:description\" content=\"Du guerrier partant batailler au laboureur souhaitant travailler, l\u2019\u00e9levage des chevaux est un art mill\u00e9naire. D\u00e9couvrez son actualit\u00e9 dans cette cat\u00e9gorie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.royal-horse.com\/fr\/wikihorse\/elevage\/\" \/>\n<meta property=\"og:site_name\" content=\"Royal Horse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/wikihorse\\\/elevage\\\/\",\"url\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/wikihorse\\\/elevage\\\/\",\"name\":\"Archives des \u00c9levage - Royal Horse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/wikihorse\\\/elevage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/wikihorse\\\/elevage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9levage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/\",\"name\":\"Royal Horse\",\"description\":\"Leader de l&#039;alimentation pour chevaux\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/#organization\",\"name\":\"Royal Horse\",\"url\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.royal-horse.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-RH.svg\",\"contentUrl\":\"https:\\\/\\\/www.royal-horse.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-RH.svg\",\"width\":71,\"height\":140,\"caption\":\"Royal Horse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.royal-horse.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des \u00c9levage - Royal Horse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.royal-horse.com\/fr\/wikihorse\/elevage\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des \u00c9levage - Royal Horse","og_description":"Du guerrier partant batailler au laboureur souhaitant travailler, l\u2019\u00e9levage des chevaux est un art mill\u00e9naire. D\u00e9couvrez son actualit\u00e9 dans cette cat\u00e9gorie.","og_url":"https:\/\/www.royal-horse.com\/fr\/wikihorse\/elevage\/","og_site_name":"Royal Horse","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.royal-horse.com\/fr\/wikihorse\/elevage\/","url":"https:\/\/www.royal-horse.com\/fr\/wikihorse\/elevage\/","name":"Archives des \u00c9levage - Royal Horse","isPartOf":{"@id":"https:\/\/www.royal-horse.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.royal-horse.com\/fr\/wikihorse\/elevage\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.royal-horse.com\/fr\/wikihorse\/elevage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.royal-horse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9levage"}]},{"@type":"WebSite","@id":"https:\/\/www.royal-horse.com\/fr\/#website","url":"https:\/\/www.royal-horse.com\/fr\/","name":"Royal Horse","description":"Leader de l&#039;alimentation pour chevaux","publisher":{"@id":"https:\/\/www.royal-horse.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.royal-horse.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.royal-horse.com\/fr\/#organization","name":"Royal Horse","url":"https:\/\/www.royal-horse.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.royal-horse.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.royal-horse.com\/wp-content\/uploads\/2021\/10\/Logo-RH.svg","contentUrl":"https:\/\/www.royal-horse.com\/wp-content\/uploads\/2021\/10\/Logo-RH.svg","width":71,"height":140,"caption":"Royal Horse"},"image":{"@id":"https:\/\/www.royal-horse.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.royal-horse.com\/fr\/wp-json\/wp\/v2\/categories\/419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.royal-horse.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.royal-horse.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.royal-horse.com\/fr\/wp-json\/wp\/v2\/posts?categories=419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}